{"id":2157,"date":"2020-01-02T22:34:46","date_gmt":"2020-01-03T03:34:46","guid":{"rendered":"https:\/\/vocamode.ca\/pe\/?page_id=2157"},"modified":"2021-05-24T17:08:20","modified_gmt":"2021-05-24T21:08:20","slug":"contact","status":"publish","type":"page","link":"https:\/\/vocamode.ca\/pe\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<h3>Questions about VOCA?<br \/>\nWe&#8217;re listening!<\/h3>\n<div id=\"mission\" class=\"sous-section-titre\">\n<h2>Contact us <i class=\"icon-right-big\"><\/i><\/h2>\n<\/div>\n<div class=\"sous-section-contenu\">\n<div class=\"content\">\n<p>By Email: <a href=\"mailto:info@vocamode.ca\"><strong>info@vocamode.ca<\/strong><\/a><\/p>\n<p>By Phone: <a href=\"tel:4509659795\"><strong>450 965-9795<\/strong><\/a><\/p>\n<p>Follow us :<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/company\/51662004\/\" class=\"\" target=\"_blank\" rel=\"noopener\" style=\"text-decoration:none;border:none;font-size:32px\"><i class=\"icon-linkedin\"><\/i><\/a><a href=\"https:\/\/www.facebook.com\/Voca.mode\/\" class=\"social\" target=\"_blank\" rel=\"noopener\" style=\"text-decoration:none;border:none;font-size:32px;margin:0 20px 0 20px\"><i class=\"icon-facebook\"><\/i><\/a><a href=\"https:\/\/www.instagram.com\/voca.mode\" class=\"social\" target=\"_blank\" rel=\"noopener\" style=\"text-decoration:none;border:none;font-size:32px\"><i class=\"icon-instagram\"><\/i><\/a><\/p>\n<p><strong>Or<\/strong><\/p>\n<p>Complete the contact form below:<\/p>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f2188-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pe\/en\/wp-json\/wp\/v2\/pages\/2157#wpcf7-f2188-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2188\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.6.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2188-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:2188,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;notice_dismissed_update-cf7-5.8.1&quot;:true}}\" \/>\n<\/div>\n<p>\t\t<div id=\"cf7md-form\" class=\"cf7md-form\">\n\t\t\t<div class=\"mdc-layout-grid\">\n\t\t\t\t<div class=\"mdc-layout-grid__inner\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-6-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap prenom\"><input type=\"text\" name=\"prenom\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">First name<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-6-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap nom\"><input type=\"text\" name=\"nom\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Last name<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\t\t\n\t\t<div class=\"cf7md-item cf7md-text mdc-layout-grid__cell mdc-layout-grid__cell--span-6-desktop mdc-layout-grid__cell--span-6-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap courriel\"><input type=\"email\" name=\"courriel\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span><br \/>\n\t\t\t<p class=\"cf7md-help-text\">name@domaine.com<\/p>\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--outlined\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Email<\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n\n\t\t<div class=\"cf7md-item cf7md-textarea mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone cf7md-textarea-autosize\">\n\t\t\t<br \/>\n<span class=\"wpcf7-form-control-wrap message\"><textarea name=\"message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span><br \/>\n\t\t\t\t\t\t<div style=\"display: none;\" class=\"cf7md-text-html\">\n\t\t\t\t<div class=\"mdc-text-field  mdc-text-field--textarea\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"mdc-notched-outline\">\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__leading\"><\/div>\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__notch\">\n\t\t\t\t\t\t\t<label class=\"mdc-floating-label\">Enter your message here<\/label>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"mdc-notched-outline__trailing\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<br \/>\n<span id=\"wpcf7-6a04e21da3490-wrapper\" class=\"wpcf7-form-control-wrap nepasremplir-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a04e21da3490-field\" class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a04e21da3490-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"nepasremplir\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span><\/p>\n<div style=\"clear:both\"><\/div>\n<p>\t\t<div class=\"cf7md-item cf7md-captcha mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\">\n\t\t\t\n<div id=\"cf7sr-6a04e21da39b8\" class=\"cf7sr-g-recaptcha\" data-theme=\"light\" data-type=\"image\" data-size=\"normal\" data-sitekey=\"6LebV8YUAAAAAD3SXKqxpHTwO3ndLdeQGnQfuRg6\"><\/div><span class=\"wpcf7-form-control-wrap cf7sr-g-recaptcha-invalid\"><\/span><br \/>\n\t\t<\/div>\n\t\t<br \/>\n\t\t<div class=\"cf7md-item cf7md-submit mdc-layout-grid__cell mdc-layout-grid__cell--span-12-desktop mdc-layout-grid__cell--span-8-tablet mdc-layout-grid__cell--span-4-phone\" data-button-style=\"raised\">\n\t\t\t<br \/>\n<input type=\"submit\" value=\"Send\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><br \/>\n\t\t\t<svg class=\"cf7md-spinner\" width=\"25px\" height=\"25px\" viewBox=\"0 0 66 66\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle class=\"cf7md-spinner-path\" fill=\"none\" stroke-width=\"6\" stroke-linecap=\"round\" cx=\"33\" cy=\"33\" r=\"30\"><\/circle>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<br \/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/p>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div style=\"clear: both;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Questions about VOCA? We&#8217;re listening! Contact us By Email: info@vocamode.ca By Phone: 450 965-9795 Follow us : Or Complete the contact form below: &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":2103,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-section.php","meta":{"footnotes":""},"categories":[],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/pages\/2157"}],"collection":[{"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/comments?post=2157"}],"version-history":[{"count":8,"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/pages\/2157\/revisions"}],"predecessor-version":[{"id":2489,"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/pages\/2157\/revisions\/2489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/media\/2103"}],"wp:attachment":[{"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/media?parent=2157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/categories?post=2157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocamode.ca\/pe\/en\/wp-json\/wp\/v2\/tags?post=2157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}